{"id":929,"date":"2013-03-16T14:39:52","date_gmt":"2013-03-16T13:39:52","guid":{"rendered":"http:\/\/www.archiviostoricodiocesibg.it\/blog\/?page_id=929"},"modified":"2024-03-28T17:59:29","modified_gmt":"2024-03-28T16:59:29","slug":"corso-2012","status":"publish","type":"page","link":"https:\/\/www.archiviostoricodiocesibg.it\/en\/archivi-parrocchiali\/attivita\/corso-2012\/","title":{"rendered":"Corso 2012"},"content":{"rendered":"<img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-1597\" alt=\"2012big\" src=\"http:\/\/www.archiviostoricodiocesibg.it\/blog\/wp-content\/uploads\/2013\/04\/2012big.png\" width=\"770\" height=\"370\" \/><\/p>\n<p><strong>PROGRAMMA DEI CORSI<\/strong><\/p>\n<p><a href=\"http:\/\/www.archiviostoricodiocesibg.it\/blog\/wp-content\/uploads\/2013\/03\/pieghevole.pdf\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft  wp-image-1014\" alt=\"Folders-Downloads-icon\" src=\"http:\/\/www.archiviostoricodiocesibg.it\/blog\/wp-content\/uploads\/2013\/02\/Folders-Downloads-icon.png\" width=\"37\" height=\"37\" \/>Scarica la brochure dell&#8217;iniziativa<\/a><\/p>\n<p>\u00a0<\/p>\n<p><strong>-&#8220;Conservare i materiali d&#8217;archivio&#8221; (31 marzo; 05 maggio; 26 maggio; 16 giugno 2012) a cura della dott.ssa\u00a0VALERIA ARENA<\/strong><\/p>\n<p>Il corso ha l&#8217;obiettivo di fornire conoscenze teoriche e pratiche di base per una corretta conservazione del materiale bibliografico-archivistico. La giornata d&#8217;aggiornamento ha un carattere spiccatamente laboratoriale e non richiede esperienze pregresse nel campo della conservazione.<\/p>\n<p><a href=\"http:\/\/www.archiviostoricodiocesibg.it\/blog\/wp-content\/uploads\/2013\/03\/Conservare-i-materiali-darchivio.pdf\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft  wp-image-1014\" alt=\"Folders-Downloads-icon\" src=\"http:\/\/www.archiviostoricodiocesibg.it\/blog\/wp-content\/uploads\/2013\/02\/Folders-Downloads-icon.png\" width=\"37\" height=\"37\" \/>Conservare i materiali d&#8217;archivio.pdf<\/a><\/p>\n<p>\u00a0<\/p>\n<p><strong>-&#8220;Il suono della scrittura: i libri corali&#8221; (13-14; 21 aprile 2012)&#8221; a cura del Mo. don GILBERTO SESSANTINI<\/strong><\/p>\n<p>Attraverso l&#8217;analisi dei libri corali, quali raffinati prodotti di legatori, calligrafi e miniatori, apprendere i principali strumenti cognitivi del canto gragoriano: la pi\u00f9 antica forma di musica sacra attestata a livello documentale fin dal Medioevo.<\/p>\n<p><a href=\"http:\/\/www.archiviostoricodiocesibg.it\/blog\/wp-content\/uploads\/2013\/03\/Liturgia-e-canto-gregoriano_Sessantini.pdf\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft  wp-image-1014\" alt=\"Folders-Downloads-icon\" src=\"http:\/\/www.archiviostoricodiocesibg.it\/blog\/wp-content\/uploads\/2013\/02\/Folders-Downloads-icon.png\" width=\"37\" height=\"37\" \/>Liturgia e Canto Gregoriano -don Gilberto Sessantini<\/a><\/p>\n<p>\u00a0<\/p>\n<p><a href=\"http:\/\/www.archiviostoricodiocesibg.it\/blog\/wp-content\/uploads\/2013\/03\/Excursus-storico_Bellinazzo.pdf\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft  wp-image-1014\" alt=\"Folders-Downloads-icon\" src=\"http:\/\/www.archiviostoricodiocesibg.it\/blog\/wp-content\/uploads\/2013\/02\/Folders-Downloads-icon.png\" width=\"37\" height=\"37\" \/>I libri del repertorio gregoriano-don Nicola Bellinazzo<\/a><\/p>\n<p>\u00a0<\/p>\n<p><a href=\"http:\/\/www.archiviostoricodiocesibg.it\/blog\/wp-content\/uploads\/2013\/03\/Evoluzione-scrittura-musicale_Vitale.pdf\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft  wp-image-1014\" alt=\"Folders-Downloads-icon\" src=\"http:\/\/www.archiviostoricodiocesibg.it\/blog\/wp-content\/uploads\/2013\/02\/Folders-Downloads-icon.png\" width=\"37\" height=\"37\" \/>Evoluzione della scrittura musicale liturgica-Stefania Vitale<\/a><\/p>\n<p>\u00a0<\/p>\n<p><a href=\"http:\/\/www.archiviostoricodiocesibg.it\/blog\/wp-content\/uploads\/2013\/03\/musica-cathedralis.pdf\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft  wp-image-1014\" alt=\"Folders-Downloads-icon\" src=\"http:\/\/www.archiviostoricodiocesibg.it\/blog\/wp-content\/uploads\/2013\/02\/Folders-Downloads-icon.png\" width=\"37\" height=\"37\" \/>Concerto &#8220;CODICES ANTIQUI&#8221;- Canto Gregoriano ed improvvisazioni organistiche- 21 aprile 2012<\/a><\/p>\n<p>\u00a0<\/p>\n<p><a href=\"http:\/\/www.archiviostoricodiocesibg.it\/blog\/wp-content\/uploads\/2013\/03\/BG1504-DOM01-53.pdf\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft  wp-image-1014\" alt=\"Folders-Downloads-icon\" src=\"http:\/\/www.archiviostoricodiocesibg.it\/blog\/wp-content\/uploads\/2013\/02\/Folders-Downloads-icon.png\" width=\"37\" height=\"37\" \/>Articolo di S. Pesenti: &#8220;Gregoriano ansia d&#8217;infinito&#8221; in &#8220;L&#8217;eco di Bergamo&#8221; 15 aprile 2012, p. 53<\/a><\/p>\n<p>\u00a0<\/p>\n<p><strong>-&#8220;Diplomatica pontificia: riconoscere i documenti ecclesiastici&#8221; (12-19 maggio 2012) a cura della dott.ssa BARBARA MARIA SCAVO<\/strong><\/p>\n<p>Conoscere e comprendere, attraverso lo studio e l&#8217;analisi della documentazione conservata in Archivio Storico Diocesano, le principali caratteristiche dei documenti ecclesiastici: scrittura, datazione, sigilli.<\/p>\n<p><a href=\"http:\/\/www.archiviostoricodiocesibg.it\/blog\/wp-content\/uploads\/2013\/03\/Diplomatica-generale-e-pontificia.pdf\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft  wp-image-1014\" alt=\"Folders-Downloads-icon\" src=\"http:\/\/www.archiviostoricodiocesibg.it\/blog\/wp-content\/uploads\/2013\/02\/Folders-Downloads-icon.png\" width=\"37\" height=\"37\" \/>Diplomatica generale e pontificia: 12-19 maggio 2012<\/a><\/p>\n<p>\u00a0<\/p>\n<p><a href=\"http:\/\/www.archiviostoricodiocesibg.it\/blog\/wp-content\/uploads\/2013\/03\/Bibliografia-TEMATICA_Laboratorio-BG.pdf\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft  wp-image-1014\" alt=\"Folders-Downloads-icon\" src=\"http:\/\/www.archiviostoricodiocesibg.it\/blog\/wp-content\/uploads\/2013\/02\/Folders-Downloads-icon.png\" width=\"37\" height=\"37\" \/>Bibliografia tematica<\/a><\/p>\n<p>\u00a0<\/p>\n<p><a href=\"http:\/\/www.archiviostoricodiocesibg.it\/blog\/wp-content\/uploads\/2013\/03\/Link_Laboratorio-ASD-BG.pdf\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft  wp-image-1014\" alt=\"Folders-Downloads-icon\" src=\"http:\/\/www.archiviostoricodiocesibg.it\/blog\/wp-content\/uploads\/2013\/02\/Folders-Downloads-icon.png\" width=\"37\" height=\"37\" \/>Link utili<\/a><\/p>\n<p>\u00a0<\/p>\n<div class='hr '><\/div>\n<p style=\"text-align: center\"><div  class='column one-third  '><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" alt=\"corso-012\" src=\"http:\/\/www.archiviostoricodiocesibg.it\/blog\/wp-content\/uploads\/2013\/04\/corso-012.png\" width=\"300\" height=\"200\" \/><\/p>\n<p style=\"text-align: center\"><\/div>\n<div  class='column one-third  '><a href=\"http:\/\/www.archiviostoricodiocesibg.it\/blog\/wp-content\/uploads\/2013\/04\/corso-012b.png\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" alt=\"corso-012b\" src=\"http:\/\/www.archiviostoricodiocesibg.it\/blog\/wp-content\/uploads\/2013\/04\/corso-012b.png\" width=\"300\" height=\"200\" \/><\/a><\/div>\n<p style=\"text-align: left\"><div  class='column one-third  last'><\/div>","protected":false},"excerpt":{"rendered":"<p>PROGRAMMA DEI CORSI Scarica la brochure dell&#8217;iniziativa \u00a0 -&#8220;Conservare i materiali d&#8217;archivio&#8221; (31 marzo; 05 maggio; 26 maggio; 16 giugno 2012) a cura della dott.ssa\u00a0VALERIA ARENA Il corso ha l&#8217;obiettivo di fornire conoscenze teoriche e pratiche di base per una corretta conservazione del materiale bibliografico-archivistico. La giornata d&#8217;aggiornamento ha un carattere spiccatamente laboratoriale e non [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":358,"menu_order":3,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-929","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/www.archiviostoricodiocesibg.it\/en\/wp-json\/wp\/v2\/pages\/929","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.archiviostoricodiocesibg.it\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.archiviostoricodiocesibg.it\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.archiviostoricodiocesibg.it\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.archiviostoricodiocesibg.it\/en\/wp-json\/wp\/v2\/comments?post=929"}],"version-history":[{"count":2,"href":"https:\/\/www.archiviostoricodiocesibg.it\/en\/wp-json\/wp\/v2\/pages\/929\/revisions"}],"predecessor-version":[{"id":6835,"href":"https:\/\/www.archiviostoricodiocesibg.it\/en\/wp-json\/wp\/v2\/pages\/929\/revisions\/6835"}],"up":[{"embeddable":true,"href":"https:\/\/www.archiviostoricodiocesibg.it\/en\/wp-json\/wp\/v2\/pages\/358"}],"wp:attachment":[{"href":"https:\/\/www.archiviostoricodiocesibg.it\/en\/wp-json\/wp\/v2\/media?parent=929"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}